{"id":45250,"date":"2021-07-09T19:54:38","date_gmt":"2021-07-09T17:54:38","guid":{"rendered":"https:\/\/www.sauter-controls.com\/produit\/smart-actuator-pour-volets-de-ventilation\/"},"modified":"2025-10-09T16:30:19","modified_gmt":"2025-10-09T14:30:19","slug":"smart-actuator-pour-volets-de-ventilation","status":"publish","type":"produit","link":"https:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/","title":{"rendered":"Smart Actuator pour volets de ventilation"},"content":{"rendered":"<p>ASM115SAF232&nbsp;<\/p>\n","protected":false},"template":"","categorieProduit":[774],"class_list":["post-45250","produit","type-produit","status-publish","hentry","categorie-produit-smart-actuators-servomoteurs-el-vannes-papillons-melangeurs"],"acf":{"link":"","image_produits_home":{"ID":49909,"id":49909,"title":"ASM 115SA: Smart Actuator f\u00fcr Luftklappen","filename":"1111691-1.png","filesize":124284,"url":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","link":"https:\/\/www.sauter-controls.com\/produkt\/smart-actuator-fuer-lueftungsklappen\/1111691-1\/","alt":"","author":"5","description":"","caption":"","name":"1111691-1","status":"inherit","uploaded_to":45236,"date":"2022-07-19 17:08:54","modified":"2022-07-19 17:10:14","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.sauter-controls.com\/wp-includes\/images\/media\/default.png","width":800,"height":517,"sizes":{"thumbnail":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-300x194.png","medium-width":300,"medium-height":194,"medium_large":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-768x496.png","medium_large-width":648,"medium_large-height":419,"large":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","large-width":648,"large-height":419,"1536x1536":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","1536x1536-width":800,"1536x1536-height":517,"2048x2048":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","2048x2048-width":800,"2048x2048-height":517,"sparkling-featured":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-750x410.png","sparkling-featured-width":750,"sparkling-featured-height":410,"sparkling-featured-fullwidth":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","sparkling-featured-fullwidth-width":800,"sparkling-featured-fullwidth-height":517,"tab-small":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-60x60.png","tab-small-width":60,"tab-small-height":60,"img-angebot":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-360x290.png","img-angebot-width":360,"img-angebot-height":290,"img-produit":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-290x333.png","img-produit-width":290,"img-produit-height":333,"img-fond":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","img-fond-width":800,"img-fond-height":517,"img-article":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-225x145.png","img-article-width":225,"img-article-height":145,"img-cadre":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-375x330.png","img-cadre-width":375,"img-cadre-height":330,"slider":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","slider-width":800,"slider-height":517,"img-prod-inno":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-480x240.png","img-prod-inno-width":480,"img-prod-inno-height":240,"img-rpoduit-interne":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-380x517.png","img-rpoduit-interne-width":380,"img-rpoduit-interne-height":517}},"image_produit_grand":{"ID":49909,"id":49909,"title":"ASM 115SA: Smart Actuator f\u00fcr Luftklappen","filename":"1111691-1.png","filesize":124284,"url":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","link":"https:\/\/www.sauter-controls.com\/produkt\/smart-actuator-fuer-lueftungsklappen\/1111691-1\/","alt":"","author":"5","description":"","caption":"","name":"1111691-1","status":"inherit","uploaded_to":45236,"date":"2022-07-19 17:08:54","modified":"2022-07-19 17:10:14","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/www.sauter-controls.com\/wp-includes\/images\/media\/default.png","width":800,"height":517,"sizes":{"thumbnail":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-300x194.png","medium-width":300,"medium-height":194,"medium_large":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-768x496.png","medium_large-width":648,"medium_large-height":419,"large":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","large-width":648,"large-height":419,"1536x1536":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","1536x1536-width":800,"1536x1536-height":517,"2048x2048":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","2048x2048-width":800,"2048x2048-height":517,"sparkling-featured":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-750x410.png","sparkling-featured-width":750,"sparkling-featured-height":410,"sparkling-featured-fullwidth":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","sparkling-featured-fullwidth-width":800,"sparkling-featured-fullwidth-height":517,"tab-small":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-60x60.png","tab-small-width":60,"tab-small-height":60,"img-angebot":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-360x290.png","img-angebot-width":360,"img-angebot-height":290,"img-produit":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-290x333.png","img-produit-width":290,"img-produit-height":333,"img-fond":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","img-fond-width":800,"img-fond-height":517,"img-article":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-225x145.png","img-article-width":225,"img-article-height":145,"img-cadre":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-375x330.png","img-cadre-width":375,"img-cadre-height":330,"slider":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1.png","slider-width":800,"slider-height":517,"img-prod-inno":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-480x240.png","img-prod-inno-width":480,"img-prod-inno-height":240,"img-rpoduit-interne":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/1111691-1-380x517.png","img-rpoduit-interne-width":380,"img-rpoduit-interne-height":517}},"title_":"Smart Actuator pour volets de ventilation","reference":"ASM115SAF232&nbsp;","description":"<div><p class=\"SectionTitle\">Votre atout en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique<\/p><p>Servomoteur de volet avec r\u00e9gulateur librement programmable int\u00e9gr\u00e9 et connexion au cloud en un seul appareil. Peut \u00eatre int\u00e9gr\u00e9 \u00e0 un syst\u00e8me d\u2019automatisation de b\u00e2timents local via BACnet ou au Cloud&nbsp;SAUTER via MQTT. Communication via WLAN et Bluetooth. Adaptation automatique au volet, commande pr\u00e9cise, efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e avec un fonctionnement des plus silencieux et fonctions intelligentes<\/p><br><\/div>","caracteristiques":"<div>\n<ul class=\"marketinglist\">\n<li>\n<p>Smart&nbsp;Actuator fonctionnant comme solution IoT intelligente pour la r\u00e9gulation autonome des applications de chauffage et de climatisation dans les Smart&nbsp;Buildings<\/p>\n<\/li>\n<li>\n<p>Des applications standard CVC pr\u00eates \u00e0 l\u2019emploi permettent une installation et une mise en service efficaces de petites installations<\/p>\n<\/li>\n<li>\n<p>Applications \u00e0 s\u00e9lectionner dans la biblioth\u00e8que depuis l\u2019application pour smartphone et \u00e0 installer sur le Smart&nbsp;Actuator<\/p>\n<\/li>\n<li>\n<p>Interfaces BACnet, Bluetooth&nbsp;LE et WLAN pour une int\u00e9gration syst\u00e8me flexible<\/p>\n<\/li>\n<li>\n<p>La mise en service, le param\u00e9trage et l\u2019acc\u00e8s \u00e0 distance \u00e0 l\u2019installation s\u2019effectuent confortablement via une application pour smartphone.<\/p>\n<\/li>\n<li>\n<p>En tant qu\u2019appareil IoT, la connexion au cloud pour l\u2019acc\u00e8s \u00e0 distance via MQTT se fait au moyen du cryptage TLS<\/p>\n<\/li>\n<li>\n<p>Les nombreuses donn\u00e9es de diagnostic du servomoteur permettent d\u2019anticiper la maintenance des installations.<\/p>\n<\/li>\n<li>\n<p>Permet la conception de r\u00e9seaux Smart&nbsp;Actuator avec intelligence distribu\u00e9e.<\/p>\n<\/li>\n<li>\n<p>En option, le Smart&nbsp;Actuator peut \u00eatre utilis\u00e9 de mani\u00e8re flexible dans les r\u00e9seaux d\u2019automatisation de b\u00e2timents gr\u00e2ce \u00e0 la programmation libre au moyen de CASE&nbsp;Suite.<\/p>\n<\/li>\n<li>\n<p>Horloge temps r\u00e9el pour les fonctions calendaires et les programmes horaires<\/p>\n<\/li>\n<li>\n<p>Deux E\/S universelles pour le raccordement de capteurs et d\u2019actionneurs externes<\/p>\n<\/li>\n<li>\n<p>Raccordement direct d\u2019un bo\u00eetier d\u2019ambiance<\/p>\n<\/li>\n<li>\n<p>Extension flexible avec jusqu\u2019\u00e0 deux modules E\/S Smart&nbsp;Actuator SAIO&nbsp;100 pour des t\u00e2ches de r\u00e9gulation compl\u00e8tes<\/p>\n<\/li>\n<li>\n<p>C\u00e2bles pr\u00e9assembl\u00e9s avec des connecteurs au codage couleur\/m\u00e9canique pour un c\u00e2blage rapide et sans erreur<\/p>\n<\/li>\n<li>\n<p>Grande simplicit\u00e9 de montage assur\u00e9e par une douille de couplage \u00e0 centrage automatique<\/p>\n<\/li>\n<li>\n<p>Fonctions de diagnostic \u00e9tendues gr\u00e2ce \u00e0 la technologie des moteurs BLDC<\/p>\n<\/li>\n<li>\n<p>Adaptation et d\u00e9tection intelligentes de l\u2019angle de rotation, avec r\u00e9trosignal<\/p>\n<\/li>\n<li>\n<p>Coupure \u00e9lectronique d\u00e9pendant du couple<\/p>\n<\/li>\n<li>\n<p>Train d\u2019engrenages d\u00e9brayable pour r\u00e9glage manuel<\/p>\n<\/li>\n<\/ul>\n<div class=\"footnotes\"><\/div>\n<\/div>\n","id_langue":"2","id_pdm":"557303","id_3ma":"acd272d5-ecac-0100-5357-210709160256","handbucher":false,"montagevorschriften":[{"titre_du_media":"ASM115SAF332","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1167301.pdf","type_de_media":"pdf","type_de_media_poids":"3 MB","indicateur_si_nouveau":[]}],"service-dokumentationen":false,"material-und-umweltdeklarationen":[{"titre_du_media":"MD ASM - FR","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1199391.doc","type_de_media":"doc","type_de_media_poids":"2 MB","indicateur_si_nouveau":[]},{"titre_du_media":"MD ASM - FR","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1201262.PDF","type_de_media":"PDF","type_de_media_poids":"381 KB","indicateur_si_nouveau":["new"]}],"prasentationen":false,"broschuren":[{"titre_du_media":"SAUTER Smart Actuator FR","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1174303.pdf","type_de_media":"pdf","type_de_media_poids":"3 MB","indicateur_si_nouveau":[]},{"titre_du_media":"Vannes et Servomoteurs","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1080966.pdf","type_de_media":"pdf","type_de_media_poids":"3 MB","indicateur_si_nouveau":[]}],"ubrige_dokumente":[{"titre_du_media":"SAUTER BACnet PICS SAUTER Smart Actuator","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1150178.PDF","type_de_media":"PDF","type_de_media_poids":"541 KB","indicateur_si_nouveau":[]},{"titre_du_media":"BTL-30942 BACnet Conformance Certificate for Smart Actuator","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1157429.pdf","type_de_media":"pdf","type_de_media_poids":"697 KB","indicateur_si_nouveau":[]},{"titre_du_media":"Poster vannes et servomoteurs - 2023","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1165409.pdf","type_de_media":"pdf","type_de_media_poids":"1 MB","indicateur_si_nouveau":[]}],"kurzbedienungsanleitungen":false,"ausschreibungstexte":false,"datenblatter":[{"titre_du_media":"ASM 115SA: Smart Actuators","adresse_du_media":"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/ImportPDM\/1165943.pdf","type_de_media":"pdf","type_de_media_poids":"2 MB","indicateur_si_nouveau":[]}],"software":false,"white_papers":false,"videos":false,"bim":[{"titre_du_media":"BIM ASM 115SA","adresse_du_media":"http:\/\/bim.sauter-controls.com\/viewitems\/drives\/asm-115sa--smart-actuator-for-ventilation-dampers","type_de_media":"BIM","type_de_media_poids":"0 KB","indicateur_si_nouveau":[]}],"typen":false,"flexible_content_sidebar":[{"acf_fc_layout":"block_title","title":"Vid\u00e9o"},{"acf_fc_layout":"block_video","iframe_video":"https:\/\/www.youtube.com\/embed\/9J7gA-haf60"},{"acf_fc_layout":"block_title","title":"Communiqu\u00e9s de presse"},{"acf_fc_layout":"Block_media_releases","media_releases":{"ID":48835,"post_author":"1661","post_date":"2022-07-07 08:39:13","post_date_gmt":"2022-07-07 06:39:13","post_content":"<em>SAUTER \u00e9largit sa gamme de produits avec la nouvelle g\u00e9n\u00e9ration de servomoteurs compatibles IoT. Le <a href=\"https:\/\/www.sauter-controls.com\/fr\/innovation\/smart-actuator\/\">Smart Actuator<\/a> permet une r\u00e9gulation autonome ou semi-autonome des \u00e9quipements de chauffage, de ventilation et de climatisation. Sa simplicit\u00e9 d\u2019installation et de mise en service, la connexion au cloud avec sa biblioth\u00e8que d\u2019applications et avec l'acc\u00e8s \u00e0 distance ainsi qu\u2019une application smartphone offrent des avantages suppl\u00e9mentaires.<\/em>\r\n\r\n[caption id=\"attachment_48829\" align=\"alignnone\" width=\"648\"]<img class=\"wp-image-48829 size-large\" src=\"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/05\/Composing-SAUTER-Smart-Actuator-Launch-1024x535.jpg\" alt=\"Repr\u00e9sentation du Smart Actuator jaune et noir avec Smartphone App et install\u00e9 dans une installation HVAC\" width=\"648\" height=\"339\" \/> Le Smart Actuator en action[\/caption]\r\n\r\nLes vannes et servomoteurs sont parmi les \u00e9l\u00e9ments les plus importants dans la distribution de l\u2019\u00e9nergie. Ils sont utilis\u00e9s dans les installations de chauffage et de ventilation ainsi que dans l\u2019automatisation de locaux. Lors de leur mise en place, les syst\u00e8mes traditionnels posent de nombreux d\u00e9fis aux op\u00e9rateurs. Le nouveau Smart Actuator de SAUTER, quant \u00e0 lui, facilite la planification, l\u2019installation et l\u2019exploitation des installations CVC dans les b\u00e2timents neufs ou modernis\u00e9s. Il offre des avantages d\u00e9cisifs \u00e0 tous les groupes d\u2019utilisateurs.\r\n<h2><strong>Simplicit\u00e9 de l\u2019installation et de la mise en service<\/strong><\/h2>\r\nLe syst\u00e8me de connecteurs muni de c\u00e2bles pr\u00e9-assembl\u00e9s garantit une installation particuli\u00e8rement rapide. Le codage m\u00e9canique et le codage couleur permettent non seulement d'\u00e9viter les erreurs de c\u00e2blage, mais aussi de r\u00e9aliser des \u00e9conomies. L\u2019application smartphone permet de charger et de configurer directement sur le Smart Actuator des applications test\u00e9es et pr\u00eates \u00e0 l\u2019emploi. Aucun logiciel suppl\u00e9mentaire n'est n\u00e9cessaire.\r\n\r\nLes appareils de terrain n\u00e9cessaires \u00e0 l\u2019application, tels que des capteurs, peuvent \u00eatre connect\u00e9s directement au servomoteur via deux E\/S universelles. Le bo\u00eetier E\/S en option permet d\u2019\u00e9tendre consid\u00e9rablement la gamme d\u2019applications.\r\n<h2><strong>Connectivit\u00e9, connexion \u00e0 l\u2019IoT et au cloud<\/strong><\/h2>\r\nLe Smart Actuator dispose d\u2019interfaces de communication pour chaque application pr\u00e9vue et s\u2019int\u00e8gre donc parfaitement dans tous les syst\u00e8mes d\u2019automatisation de b\u00e2timents. Si un r\u00e9seau d\u2019automatisation de b\u00e2timents existe d\u00e9j\u00e0, le Smart Actuator s'int\u00e8gre via <a href=\"http:\/\/www.bacnet.org\/\">BACnet<\/a> MS\/TP. Gr\u00e2ce \u00e0 la fonction d\u2019acc\u00e8s \u00e0 distance au Cloud SAUTER, les installateurs, les techniciens de service et les facility managers peuvent acc\u00e9der aux donn\u00e9es d\u2019exploitation, aux r\u00e9glages et \u00e0 la r\u00e9gulation du Smart Actuator \u00e0 l'aide de leur smartphone. En absence de connexion r\u00e9seau, il est possible d\u2019acc\u00e9der via Bluetooth LE \u00e0 toutes les donn\u00e9es du Smart Actuator. Finalement, une biblioth\u00e8que de solutions est aussi disponible sur le Cloud.\r\n<h2><strong>R\u00e9gulation semi-autonome ou m\u00eame autonome pour l\u2019intelligence distribu\u00e9e<\/strong><\/h2>\r\nLes t\u00e2ches de r\u00e9gulation d\u00e9centralis\u00e9es sont effectu\u00e9es de mani\u00e8re autonome par le Smart Actuator sans que des unit\u00e9s de gestion locale suppl\u00e9mentaires ne soient n\u00e9cessaires. Il est ainsi m\u00eame possible de se passer compl\u00e8tement d\u2019une automatisation centrale de l\u2019installation. Si cela n\u2019est pas souhait\u00e9, il est possible d'utiliser des interfaces d\u2019int\u00e9gration syst\u00e8me permettant une r\u00e9gulation semi-autonome au sein de l\u2019ensemble du syst\u00e8me.\r\n\r\n&nbsp;\r\n\r\nAvantages de l\u2019intelligence distribu\u00e9e :\r\n<ul>\r\n \t<li>Syst\u00e8mes plus robustes, pas de \u00ab Single Point of Failure \u00bb<\/li>\r\n \t<li>Utilisation r\u00e9duite des ressources (pas de faisceaux de c\u00e2bles ni de co\u00fbts de c\u00e2blage)<\/li>\r\n \t<li>Installations plus compactes, armoires de commande plus petites, charges calorifiques plus faibles<\/li>\r\n \t<li>Meilleure modularit\u00e9 de l\u2019installation<\/li>\r\n \t<li>Structure logicielle et mat\u00e9rielle simplifi\u00e9e, quelle que soit l\u2019architecture<\/li>\r\n<\/ul>\r\n&nbsp;\r\n\r\nLe<a href=\"https:\/\/www.sauter-controls.com\/fr\/innovation\/smart-actuator\/\"> Smart Actuator<\/a> sera disponible \u00e0 partir de l\u2019\u00e9t\u00e9 2022. Pour les d\u00e9monstrations de produits, veuillez <a href=\"https:\/\/www.sauter-controls.com\/fr\/entreprise\/contactez-nous\/\" target=\"_blank\" rel=\"noopener noreferrer\">contacter le service commercial<\/a>.\r\n\r\nApprenez-en plus sur le Smart Actuator avec <a href=\"https:\/\/www.youtube.com\/watch?v=9J7gA-haf60\">notre vid\u00e9o sur Youtube.<\/a>\r\n\r\n<a href=\"https:\/\/www.sauter-controls.com\/wp-content\/uploads\/2022\/07\/Lancement-du-produit-Smart-Actuator-IoT-pour-nouvelles-constructions-et-modernisations-de-b\u00e2timents.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">T\u00e9l\u00e9charger communiqu\u00e9 de presse<\/a>\r\n\r\n&nbsp;\r\n<h3>\u00c0 propos de SAUTER<\/h3>\r\n<em>En tant que premier prestataire mondial de solutions\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/innovation\/gestion-technique-de-batiments\/\" target=\"_blank\" rel=\"noopener noreferrer\">d\u2019automatisation des \u00ab Green Buildings \u00bb<\/a>, SAUTER assure le confort et le climat ambiant optimal dans les environnements durables. Sp\u00e9cialiste en la mati\u00e8re, SAUTER d\u00e9veloppe, fabrique et commercialise des produits et des syst\u00e8mes pour des solutions globales \u00e9co\u00e9nerg\u00e9tiques, et assure l\u2019exploitation optimis\u00e9e en \u00e9nergie des b\u00e2timents gr\u00e2ce \u00e0 des prestations de service \u00e9tendues. De la planification \u00e0 l\u2019exploitation, en passant par la r\u00e9alisation, ces produits, solutions et prestations permettent d\u2019assurer durant tout le cycle de vie du b\u00e2timent une haute efficacit\u00e9 \u00e9nerg\u00e9tique dans les\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/burogebaude\/\" target=\"_blank\" rel=\"noopener noreferrer\">bureaux, les immeubles administratifs<\/a>,\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/bildung\/\" target=\"_blank\" rel=\"noopener noreferrer\">les centres de recherche et de formation<\/a>,\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/sante\/\" target=\"_blank\" rel=\"noopener noreferrer\">les h\u00f4pitaux<\/a>,\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/industrie\/\" target=\"_blank\" rel=\"noopener noreferrer\">les b\u00e2timents industriels<\/a>,\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/life-science\/\" target=\"_blank\" rel=\"noopener noreferrer\">les laboratoires<\/a>,\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/oeffentliche-gebaeude\/\" target=\"_blank\" rel=\"noopener noreferrer\">les a\u00e9roports<\/a>,\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/freizeit\/\" target=\"_blank\" rel=\"noopener noreferrer\">les centres de loisirs<\/a>,\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/secteurs\/hotel\/\" target=\"_blank\" rel=\"noopener noreferrer\">les h\u00f4tels<\/a>\u00a0ou les centres de gestion des donn\u00e9es. Fort de plus de 100 ans d\u2019exp\u00e9rience et de comp\u00e9tences technologiques \u00e9prouv\u00e9es, SAUTER est un int\u00e9grateur de syst\u00e8mes confirm\u00e9, garantissant une innovation permanente et une qualit\u00e9 suisse. SAUTER fournit aux utilisateurs comme aux exploitants une vue d\u2019ensemble de leur consommation et de leurs flux d\u2019\u00e9nergie, et donc de l\u2019\u00e9volution des co\u00fbts.<\/em>\r\n\r\n&nbsp;\r\n<h3>Groupe SAUTER<\/h3>\r\n<ul>\r\n \t<li>Entreprise domicili\u00e9e \u00e0 B\u00e2le (Suisse) et op\u00e9rant \u00e0 l\u2019\u00e9chelle mondiale<\/li>\r\n \t<li>Fond\u00e9e en 1910, jouissant de plus de\u00a0<a href=\"https:\/\/www.sauter-controls.com\/fr\/unternehmen\/histoire\/\">100\u00a0ans de tradition<\/a>\u00a0et d\u2019exp\u00e9rience<\/li>\r\n \t<li>Emploie plus de 3300 collaborateurs dans le monde entier<\/li>\r\n \t<li>Solutions compl\u00e8tes tout-en-un de gestion technique de b\u00e2timents\r\nSouci primaire\u00a0: efficacit\u00e9 \u00e9nerg\u00e9tique maximale et d\u00e9veloppement durable<\/li>\r\n \t<li>S\u00e9curit\u00e9 des investissements et de l\u2019exploitation pendant tout le cycle de vie du b\u00e2timent<\/li>\r\n \t<li>Entreprise leader en mati\u00e8re de technologies pour l\u2019automatisation de b\u00e2timents et l\u2019int\u00e9gration syst\u00e8me<\/li>\r\n \t<li>Membre d\u2019<a href=\"https:\/\/www.eubac.org\/home\/index.html\">eu.bac<\/a>, de\u00a0<a href=\"https:\/\/www.big-eu.org\/en\/\">BACnet Interest Group (BIG-EU)<\/a>,\u00a0<a href=\"https:\/\/www.bacnetinternational.org\/\">BACnet International<\/a>,\u00a0<a href=\"https:\/\/www.enocean.com\/en\/\">EnOcean Alliance<\/a><\/li>\r\n<\/ul>\r\n&nbsp;","post_title":"Lancement du produit Smart Actuator : IoT pour nouvelles constructions et modernisations de b\u00e2timents","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"lancement-du-produit-smart-actuator-iot-pour-nouvelles-constructions-et-modernisations-de-batiments","to_ping":"","pinged":"","post_modified":"2022-07-07 08:39:13","post_modified_gmt":"2022-07-07 06:39:13","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.sauter-controls.com\/?p=48835","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"}}],"number_id_pc":"53.300","pro_file":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Smart Actuator pour volets de ventilation ASM115SAF232&nbsp; \u25ba SAUTER Controls<\/title>\n<meta name=\"description\" content=\"ASM115SAF232&nbsp; | Votre atout en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tiqueServomoteur de volet avec r\u00e9gulateur librement programmable int\u00e9gr\u00e9 et connexion au cloud en un seul appareil. Peut \u00eatre int\u00e9gr\u00e9 \u00e0 un syst\u00e8me d\u2019automatisation de b\u00e2timents local via BACnet ou au Cloud&nbsp;SAUTER via MQTT. Communication via WLAN et Bluetooth. Adaptation automatique au volet, commande pr\u00e9cise, efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e avec un fonctionnement des plus silencieux et fonctions intelligentes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart Actuator pour volets de ventilation ASM115SAF232&nbsp; \u25ba SAUTER Controls\" \/>\n<meta property=\"og:description\" content=\"ASM115SAF232&nbsp; | Votre atout en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tiqueServomoteur de volet avec r\u00e9gulateur librement programmable int\u00e9gr\u00e9 et connexion au cloud en un seul appareil. Peut \u00eatre int\u00e9gr\u00e9 \u00e0 un syst\u00e8me d\u2019automatisation de b\u00e2timents local via BACnet ou au Cloud&nbsp;SAUTER via MQTT. Communication via WLAN et Bluetooth. Adaptation automatique au volet, commande pr\u00e9cise, efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e avec un fonctionnement des plus silencieux et fonctions intelligentes\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/\" \/>\n<meta property=\"og:site_name\" content=\"sauter-controls.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T14:30:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/\",\"url\":\"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/\",\"name\":\"Smart Actuator pour volets de ventilation ASM115SAF232&nbsp; \u25ba SAUTER Controls\",\"isPartOf\":{\"@id\":\"https:\/\/www.sauter-controls.com\/en\/#website\"},\"datePublished\":\"2021-07-09T17:54:38+00:00\",\"dateModified\":\"2025-10-09T14:30:19+00:00\",\"description\":\"ASM115SAF232&nbsp; | Votre atout en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique Servomoteur de volet avec r\u00e9gulateur librement programmable int\u00e9gr\u00e9 et connexion au cloud en un seul appareil. Peut \u00eatre int\u00e9gr\u00e9 \u00e0 un syst\u00e8me d\u2019automatisation de b\u00e2timents local via BACnet ou au Cloud&nbsp;SAUTER via MQTT. Communication via WLAN et Bluetooth. Adaptation automatique au volet, commande pr\u00e9cise, efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e avec un fonctionnement des plus silencieux et fonctions intelligentes\",\"breadcrumb\":{\"@id\":\"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sauter-controls.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smart Actuator pour volets de ventilation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sauter-controls.com\/en\/#website\",\"url\":\"https:\/\/www.sauter-controls.com\/en\/\",\"name\":\"sauter-controls.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sauter-controls.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smart Actuator pour volets de ventilation ASM115SAF232&nbsp; \u25ba SAUTER Controls","description":"ASM115SAF232&nbsp; | Votre atout en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tiqueServomoteur de volet avec r\u00e9gulateur librement programmable int\u00e9gr\u00e9 et connexion au cloud en un seul appareil. Peut \u00eatre int\u00e9gr\u00e9 \u00e0 un syst\u00e8me d\u2019automatisation de b\u00e2timents local via BACnet ou au Cloud&nbsp;SAUTER via MQTT. Communication via WLAN et Bluetooth. Adaptation automatique au volet, commande pr\u00e9cise, efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e avec un fonctionnement des plus silencieux et fonctions intelligentes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/","og_locale":"fr_FR","og_type":"article","og_title":"Smart Actuator pour volets de ventilation ASM115SAF232&nbsp; \u25ba SAUTER Controls","og_description":"ASM115SAF232&nbsp; | Votre atout en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tiqueServomoteur de volet avec r\u00e9gulateur librement programmable int\u00e9gr\u00e9 et connexion au cloud en un seul appareil. Peut \u00eatre int\u00e9gr\u00e9 \u00e0 un syst\u00e8me d\u2019automatisation de b\u00e2timents local via BACnet ou au Cloud&nbsp;SAUTER via MQTT. Communication via WLAN et Bluetooth. Adaptation automatique au volet, commande pr\u00e9cise, efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e avec un fonctionnement des plus silencieux et fonctions intelligentes","og_url":"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/","og_site_name":"sauter-controls.com","article_modified_time":"2025-10-09T14:30:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/","url":"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/","name":"Smart Actuator pour volets de ventilation ASM115SAF232&nbsp; \u25ba SAUTER Controls","isPartOf":{"@id":"https:\/\/www.sauter-controls.com\/en\/#website"},"datePublished":"2021-07-09T17:54:38+00:00","dateModified":"2025-10-09T14:30:19+00:00","description":"ASM115SAF232&nbsp; | Votre atout en mati\u00e8re d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique Servomoteur de volet avec r\u00e9gulateur librement programmable int\u00e9gr\u00e9 et connexion au cloud en un seul appareil. Peut \u00eatre int\u00e9gr\u00e9 \u00e0 un syst\u00e8me d\u2019automatisation de b\u00e2timents local via BACnet ou au Cloud&nbsp;SAUTER via MQTT. Communication via WLAN et Bluetooth. Adaptation automatique au volet, commande pr\u00e9cise, efficacit\u00e9 \u00e9nerg\u00e9tique \u00e9lev\u00e9e avec un fonctionnement des plus silencieux et fonctions intelligentes","breadcrumb":{"@id":"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.sauter-controls.com\/fr\/produkt\/smart-actuator-pour-volets-de-ventilation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sauter-controls.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Smart Actuator pour volets de ventilation"}]},{"@type":"WebSite","@id":"https:\/\/www.sauter-controls.com\/en\/#website","url":"https:\/\/www.sauter-controls.com\/en\/","name":"sauter-controls.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sauter-controls.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sauter-controls.com\/fr\/wp-json\/wp\/v2\/produits\/45250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sauter-controls.com\/fr\/wp-json\/wp\/v2\/produits"}],"about":[{"href":"https:\/\/www.sauter-controls.com\/fr\/wp-json\/wp\/v2\/types\/produit"}],"wp:attachment":[{"href":"https:\/\/www.sauter-controls.com\/fr\/wp-json\/wp\/v2\/media?parent=45250"}],"wp:term":[{"taxonomy":"categorie-produit","embeddable":true,"href":"https:\/\/www.sauter-controls.com\/fr\/wp-json\/wp\/v2\/categorieProduit?post=45250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}